{"id":51021,"date":"2024-02-27T20:16:34","date_gmt":"2024-02-27T19:16:34","guid":{"rendered":"https:\/\/www.secuinfra.com\/?page_id=51021"},"modified":"2026-07-08T15:08:26","modified_gmt":"2026-07-08T13:08:26","slug":"data-breach-assessment","status":"publish","type":"page","link":"https:\/\/www.secuinfra.com\/de\/incident-management\/data-breach-assessment\/","title":{"rendered":"Data Breach Assessment"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-flat ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">[inhalt_uebersetzt]<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/meldepfilchten-bei-einem-it-security-incident\/#Was_muss_gemeldet_werden\" >Was muss gemeldet werden?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/meldepfilchten-bei-einem-it-security-incident\/#Wann_muss_eine_Stoerung_gemeldet_werden\" >Wann muss eine St\u00f6rung gemeldet werden?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/meldepfilchten-bei-einem-it-security-incident\/#Wer_muss_eine_Stoerung_melden\" >Wer muss eine St\u00f6rung melden?<\/a><\/li><\/ul><\/nav><\/div>\n\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"51021\" class=\"elementor elementor-51021\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61728e5 header e-flex e-con-boxed e-con e-parent\" data-id=\"61728e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c4e51ba e-con-full e-flex e-con e-child\" data-id=\"c4e51ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cabd35 rot elementor-widget elementor-widget-heading\" data-id=\"0cabd35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Data Breach Assessment<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90f196b verlauf elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"90f196b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Identifizieren Sie gestohlene Daten \nbevor Angreifer sie gezielt ausnutzen!<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32f0e58 checkliste elementor-widget elementor-widget-text-editor\" data-id=\"32f0e58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Erkennen Sie Datenlecks so fr\u00fch wie m\u00f6glich, unabh\u00e4ngig davon, ob sie intern oder durch Dritte entstanden sind.<\/li><li>Verstehen und reduzieren Sie Ihre Angriffsfl\u00e4che.<\/li><li>Typosquatting-Sites effizient identifizieren und schlie\u00dfen lassen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae811cc elementor-hidden-mobile e-con-full e-flex e-con e-child\" data-id=\"ae811cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c8467f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c8467f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5c59cef elementor-invisible\" data-id=\"5c59cef\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-776e4ee rot elementor-widget elementor-widget-heading\" data-id=\"776e4ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-large\">250+<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dea974 elementor-widget elementor-widget-heading\" data-id=\"8dea974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-medium\">Aktive Quellen im<br> \nDarkweb &amp; Clearweb<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-339ea39 elementor-invisible\" data-id=\"339ea39\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c48404 rot elementor-widget elementor-widget-heading\" data-id=\"9c48404\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-large\">2 Millionen<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9869166 elementor-widget elementor-widget-heading\" data-id=\"9869166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-medium\">neue Events pro Tag<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-36c9b86 elementor-invisible\" data-id=\"36c9b86\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c8158 rot elementor-widget elementor-widget-heading\" data-id=\"69c8158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-large\">80+<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59b91c0 elementor-widget elementor-widget-heading\" data-id=\"59b91c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-medium\">Cyber Defense Experten <br>f\u00fcr schnelle Hilfe<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df831bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df831bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-626b3ed\" data-id=\"626b3ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a0cb45 elementor-align-center button_gruen elementor-widget elementor-widget-button\" data-id=\"8a0cb45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19a1647 verlauf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19a1647\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d70732\" data-id=\"4d70732\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-372ac2c zitat elementor-widget elementor-widget-text-editor\" data-id=\"372ac2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nutzen Sie das Data Breach Assessment, um herauszufinden, welche Ihrer Zugangsdaten bereits verkauft wurden und welche externe Angriffsoberfl\u00e4che Ihr Unternehmen bietet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48a8a4e hintergrund_weiss elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48a8a4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ce1d3e\" data-id=\"1ce1d3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d81cab gruen elementor-widget elementor-widget-heading\" data-id=\"5d81cab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Data Breach Assessment - Datenabfluss fr\u00fch erkennen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2aee41 elementor-widget elementor-widget-text-editor\" data-id=\"b2aee41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-teams=\"true\">Angreifer nutzen h\u00e4ufig legitime, kompromittierte Zugangsdaten, um in Unternehmen einzudringen. Da sie sich auf g\u00e4ngigem Wege anmelden, ist die Unterscheidung zwischen einem legitimen und malizi\u00f6sen Login oft schwierig auszumachen. Diese Zugangsdaten werden auf zwei unterschiedlichen Wegen erbeutet:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb3c438 e-grid e-con-boxed e-con e-parent\" data-id=\"fb3c438\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbfd21b elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bbfd21b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shield-virus\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224,192a16,16,0,1,0,16,16A16,16,0,0,0,224,192ZM466.5,83.68l-192-80A57.4,57.4,0,0,0,256.05,0a57.4,57.4,0,0,0-18.46,3.67l-192,80A47.93,47.93,0,0,0,16,128C16,326.5,130.5,463.72,237.5,508.32a48.09,48.09,0,0,0,36.91,0C360.09,472.61,496,349.3,496,128A48,48,0,0,0,466.5,83.68ZM384,256H371.88c-28.51,0-42.79,34.47-22.63,54.63l8.58,8.57a16,16,0,1,1-22.63,22.63l-8.57-8.58C306.47,313.09,272,327.37,272,355.88V368a16,16,0,0,1-32,0V355.88c0-28.51-34.47-42.79-54.63-22.63l-8.57,8.58a16,16,0,0,1-22.63-22.63l8.58-8.57c20.16-20.16,5.88-54.63-22.63-54.63H128a16,16,0,0,1,0-32h12.12c28.51,0,42.79-34.47,22.63-54.63l-8.58-8.57a16,16,0,0,1,22.63-22.63l8.57,8.58c20.16,20.16,54.63,5.88,54.63-22.63V112a16,16,0,0,1,32,0v12.12c0,28.51,34.47,42.79,54.63,22.63l8.57-8.58a16,16,0,0,1,22.63,22.63l-8.58,8.57C329.09,189.53,343.37,224,371.88,224H384a16,16,0,0,1,0,32Zm-96,0a16,16,0,1,0,16,16A16,16,0,0,0,288,256Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIm Webbrowser gespeicherte Zugangsdaten werden von einem Computer ausgeleitet, welcher mit Infostealer Schadsoftware kompromittiert wurde. Diese Zug\u00e4nge werden \u00fcber Marktpl\u00e4tze oder Foren im Darknet und auf Chat-Plattformen verkauft.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a195ada elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a195ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-shield-virus\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224,192a16,16,0,1,0,16,16A16,16,0,0,0,224,192ZM466.5,83.68l-192-80A57.4,57.4,0,0,0,256.05,0a57.4,57.4,0,0,0-18.46,3.67l-192,80A47.93,47.93,0,0,0,16,128C16,326.5,130.5,463.72,237.5,508.32a48.09,48.09,0,0,0,36.91,0C360.09,472.61,496,349.3,496,128A48,48,0,0,0,466.5,83.68ZM384,256H371.88c-28.51,0-42.79,34.47-22.63,54.63l8.58,8.57a16,16,0,1,1-22.63,22.63l-8.57-8.58C306.47,313.09,272,327.37,272,355.88V368a16,16,0,0,1-32,0V355.88c0-28.51-34.47-42.79-54.63-22.63l-8.57,8.58a16,16,0,0,1-22.63-22.63l8.58-8.57c20.16-20.16,5.88-54.63-22.63-54.63H128a16,16,0,0,1,0-32h12.12c28.51,0,42.79-34.47,22.63-54.63l-8.58-8.57a16,16,0,0,1,22.63-22.63l8.57,8.58c20.16,20.16,54.63,5.88,54.63-22.63V112a16,16,0,0,1,32,0v12.12c0,28.51,34.47,42.79,54.63,22.63l8.57-8.58a16,16,0,0,1,22.63,22.63l-8.58,8.57C329.09,189.53,343.37,224,371.88,224H384a16,16,0,0,1,0,32Zm-96,0a16,16,0,1,0,16,16A16,16,0,0,0,288,256Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMitarbeiter registrieren sich mit ihrer beruflichen E-Mail Adresse bei Drittanbietern. Kommt es dort zu einem Sicherheitsvorfall, werden oft die Nutzerdatenbanken dieser Dienste kompromittiert und an andere Cyberkriminelle weiterverkauft.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7370f7 elementor-widget elementor-widget-spacer\" data-id=\"c7370f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b23620 elementor-widget elementor-widget-heading\" data-id=\"1b23620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Was bietet unser Data Breach Assessment Service?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-190376f elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"190376f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDark Web Monitoring\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir \u00fcberwachen kontinuierlich Quellen, die auf die Ver\u00f6ffentlichung oder den Verkauf Ihrer Daten hinweisen, und informieren Sie sofort, wenn es zu einem Vorfall kommt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9e2f70 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a9e2f70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSchutz vor Typosquatting\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir identifizieren fr\u00fchzeitig \u00e4hnliche Domains und unterst\u00fctzen Sie bei der Deaktivierung solcher Bedrohungen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1cdca1 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a1cdca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00dcberwachung von Lieferketten und Partnerunternehmen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPotentiell gef\u00e4hrdete Lieferanten oder Partner werden u.a. auf Ransomware Leaks \u00fcberwacht. Sollten relevante Informationen ver\u00f6ffentlicht werden, werden Sie umgehend informiert.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf09b92 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bf09b92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAnalyse internet-exponierter Systeme\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRegelm\u00e4\u00dfige Scans Ihrer Systeme decken bekannte Schwachstellen (CVEs) auf.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25e3682 elementor-widget elementor-widget-text-editor\" data-id=\"25e3682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mit unserem Tool-gest\u00fctzten Ansatz identifizieren wir Spuren im Internet und Darknet, insbesondere f\u00fcr kritische Systeme und VIPs wie die Gesch\u00e4ftsleitung. So minimieren Sie den Aufwand und maximieren die Effizienz Ihrer Cyber Threat Intelligence.<\/p><p><strong>Sch\u00fctzen Sie Ihr Unternehmen proaktiv &#8211; mit dem Data Breach Assessment von SECUINFRA!\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af67afd elementor-widget elementor-widget-text-editor\" data-id=\"af67afd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Um die Gefahren zu visualisieren und die Bedrohung verst\u00e4ndlicher zu machen, betrachten wir folgendes Beispiel:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-235f708 elementor-widget elementor-widget-image\" data-id=\"235f708\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"573\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Grafik_Data-Breach-Assessment_DE_Gruen-1-800x573.png\" class=\"attachment-medium size-medium wp-image-51337\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Grafik_Data-Breach-Assessment_DE_Gruen-1-800x573.png 800w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Grafik_Data-Breach-Assessment_DE_Gruen-1-1600x1146.png 1600w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Grafik_Data-Breach-Assessment_DE_Gruen-1-768x550.png 768w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Grafik_Data-Breach-Assessment_DE_Gruen-1-1536x1100.png 1536w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Grafik_Data-Breach-Assessment_DE_Gruen-1-2048x1467.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Ein Mitarbeiter f\u00e4ngt sich auf seinem privaten Rechner einen Infostealer ein, der unter anderem Zugangsdaten aus dem Browser ausliest. Durch die Synchronisation des Browser-Accounts zwischen Privat- und Firmencomputer gelangen auch Zugangsdaten des Unternehmens in die H\u00e4nde der Angreifer. Diese Zugangsdaten werden zum Verkauf angeboten und innerhalb k\u00fcrzester Zeit von anderen Cyberkriminellen erworben. Darunter befinden sich auch die VPN-Zugangsdaten, die den Cyberkriminellen den Zugriff auf das Firmennetzwerk erm\u00f6glichen. So k\u00f6nnen Angreifer in k\u00fcrzester Zeit erheblichen Schaden anrichten.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-127e7df hintergrund_grau elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"127e7df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e82bfae\" data-id=\"e82bfae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f829483 zitat gruen elementor-widget elementor-widget-text-editor\" data-id=\"f829483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir helfen Ihnen, gestohlene Daten und kompromittierte Systeme schnell und effizient zu identifizieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f35c4e elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"0f35c4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hannah Riemer, DFIR<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0667c32\" data-id=\"0667c32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-059fd0c elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-height-default\" data-id=\"059fd0c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63f8b34 elementor-hidden-desktop elementor-hidden-tablet\" data-id=\"63f8b34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-567b12f elementor-widget elementor-widget-text-editor\" data-id=\"567b12f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hannah Riemer, DFIR<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4956a91\" data-id=\"4956a91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb3f99 elementor-widget elementor-widget-image\" data-id=\"bbb3f99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"1000\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Riemer-Hannah-stl-1.png\" class=\"attachment-full size-full wp-image-64201\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Riemer-Hannah-stl-1.png 1200w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Riemer-Hannah-stl-1-800x667.png 800w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Riemer-Hannah-stl-1-768x640.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a241745 e-flex e-con-boxed e-con e-parent\" data-id=\"a241745\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-437355d elementor-widget elementor-widget-heading\" data-id=\"437355d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie wir Data Breach Assessments durchf\u00fchren\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2612da9 elementor-widget elementor-widget-spacer\" data-id=\"2612da9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4afc7ae e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"4afc7ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"78628782\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-786287821\" data-tab-title-id=\"e-n-tab-title-786287821\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-786287821\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t1. Konfiguration\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-786287822\" data-tab-title-id=\"e-n-tab-title-786287822\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-786287822\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t2. Scan\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-786287823\" data-tab-title-id=\"e-n-tab-title-786287823\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-786287823\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t3. Analyse\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-786287824\" data-tab-title-id=\"e-n-tab-title-786287824\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-786287824\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\t4. Reporting\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-786287821\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-786287821\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-f40bf11 e-con-full e-flex e-con e-child\" data-id=\"f40bf11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11e4581 elementor-widget elementor-widget-text-editor\" data-id=\"11e4581\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5731db elementor-widget elementor-widget-text-editor\" data-id=\"e5731db\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>In der Konfigurationsphase w\u00e4hlen wir gemeinsam mit Ihnen geeignete Selektoren f\u00fcr die Suche nach Ihren Unternehmensdaten aus. Selektoren k\u00f6nnen unter anderem URLs, IPs, Benutzer-\/E-Mail-Adressen, Sicherheitsschl\u00fcssel usw. sein. Um einen umfassenden \u00dcberblick zu erhalten, empfiehlt die SECUINFRA, sich auf kritische Systeme zu konzentrieren, wie z.B:<\/p><ul><li>Ihre Unternehmensdom\u00e4ne oder Active Directory-Dom\u00e4ne<\/li><li>Hostnamen oder IP-Adressen \u00f6ffentlich zug\u00e4nglicher Systeme wie Firewalls oder VPN-Gateways<\/li><li>E-Mail-Adressen von VIP-Benutzern (Mitglieder der Gesch\u00e4ftsleitung oder Administratoren \u2013 Mitarbeiter mit erweiterten Rechten auf IT-Systemen).<\/li><\/ul><p>Diese werden dann f\u00fcr den Dienst konfiguriert und der Scan gestartet.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-786287822\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-786287822\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-1ad29c9 e-con-full e-flex e-con e-child\" data-id=\"1ad29c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef303a7 elementor-widget elementor-widget-text-editor\" data-id=\"ef303a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e488b4 elementor-widget elementor-widget-text-editor\" data-id=\"3e488b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>Der Ablauf der Scan-Phase h\u00e4ngt vom gew\u00e4hlten Servicepaket ab:<\/p><p><strong>AdHoc Data Breach Assessment (Bewertung von Datenpannen)<\/strong><br \/>In unserem AdHoc Service werden alle eingehenden Ereignisse von unseren Experten kategorisiert, analysiert und bewertet. Bei einem identifizierten Sicherheitsvorfall werden Sie umgehend informiert.<\/p><p><strong>Kontinuierliches Data Breach Assessment<\/strong><br \/>Bei unserem Continuous Service wird der initiale Scan der Systeme als sogenannter Baseline Scan betrachtet. Er gibt einen qualitativen \u00dcberblick \u00fcber die aktuelle Sicherheits- und Risikosituation in Bezug auf die betrachteten Selektoren. In regelm\u00e4\u00dfigen Intervallen werden Follow-up Scans durchgef\u00fchrt, die auf dem Baseline Scan aufbauen und bei denen nur die Ver\u00e4nderungen betrachtet werden. Insbesondere durch das Continuous Data Breach Assessment wird die Analyse mit jedem weiteren Follow-Up effizienter und Exfiltrationen bzw. gestohlene Daten k\u00f6nnen deutlich schneller erkannt werden, bevor Angreifer diese explizit ausnutzen k\u00f6nnen.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-786287823\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-786287823\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-b111289 e-con-full e-flex e-con e-child\" data-id=\"b111289\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2054c20 elementor-widget elementor-widget-text-editor\" data-id=\"2054c20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In der Analysephase untersuchen unsere Cyber Defense-Experten die Scan-Ergebnisse und identifizieren gestohlene Daten und kompromittierte IT-Systeme. Die Ereignisse werden beschrieben, in Kritikalit\u00e4tsklassen eingeteilt und mit klaren Handlungsempfehlungen versehen. Bei besonders kritischen Ergebnissen werden Sie umgehend informiert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-786287824\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-786287824\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-33f0b4c e-flex e-con-boxed e-con e-child\" data-id=\"33f0b4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f115ec9 elementor-widget elementor-widget-text-editor\" data-id=\"f115ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nach jedem Scan erhalten Sie einen ausf\u00fchrlichen Bericht mit allen sicherheitsrelevanten Ergebnissen, detaillierten Beschreibungen, Bewertungen und klaren Handlungsempfehlungen. Der Bericht wird Ihnen in einer Videokonferenz pr\u00e4sentiert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d9d18 elementor-widget elementor-widget-image\" data-id=\"32d9d18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"336\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Vorgehensweise_Data-Breach-Assessment-DE-800x336.png\" class=\"attachment-medium size-medium wp-image-51176\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Vorgehensweise_Data-Breach-Assessment-DE-800x336.png 800w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Vorgehensweise_Data-Breach-Assessment-DE-1600x671.png 1600w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Vorgehensweise_Data-Breach-Assessment-DE-768x322.png 768w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Vorgehensweise_Data-Breach-Assessment-DE-1536x644.png 1536w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/Vorgehensweise_Data-Breach-Assessment-DE-2048x859.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2a67d5 elementor-section-full_width hintergrund_grau elementor-section-height-default elementor-section-height-default\" data-id=\"b2a67d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-905caa3\" data-id=\"905caa3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae7677 gruen elementor-widget elementor-widget-heading\" data-id=\"7ae7677\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zertifizierungen unserer Experten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e3a002d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e3a002d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-2565084\" data-id=\"2565084\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d620c90 elementor-widget elementor-widget-image\" data-id=\"d620c90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/auszeichnungen_gcih_scaled.png\" class=\"attachment-full size-full wp-image-37851\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled.png 340w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled-300x300.png 300w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled-150x150.png 150w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled-60x60.png 60w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled-24x24.png 24w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled-36x36.png 36w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcih_scaled-48x48.png 48w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-18b0f60\" data-id=\"18b0f60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7f99a5 elementor-widget elementor-widget-image\" data-id=\"c7f99a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/auszeichnungen_gicp_scaled.png\" class=\"attachment-full size-full wp-image-37853\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled.png 340w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled-300x300.png 300w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled-150x150.png 150w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled-60x60.png 60w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled-24x24.png 24w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled-36x36.png 36w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gicp_scaled-48x48.png 48w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-b9bb59c\" data-id=\"b9bb59c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b63e6f elementor-widget elementor-widget-image\" data-id=\"5b63e6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/auszeichnungen_gcfe_scaled.png\" class=\"attachment-full size-full wp-image-37847\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled.png 340w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled-300x300.png 300w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled-150x150.png 150w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled-60x60.png 60w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled-24x24.png 24w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled-36x36.png 36w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcfe_scaled-48x48.png 48w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-7f8a555\" data-id=\"7f8a555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a84282d elementor-widget elementor-widget-image\" data-id=\"a84282d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/auszeichnungen_gnfa_scaled.png\" class=\"attachment-full size-full wp-image-37857\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled.png 340w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled-300x300.png 300w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled-150x150.png 150w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled-60x60.png 60w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled-24x24.png 24w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled-36x36.png 36w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gnfa_scaled-48x48.png 48w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-d1ed02b\" data-id=\"d1ed02b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a8fcd7 elementor-widget elementor-widget-image\" data-id=\"5a8fcd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/auszeichnungen_gcia_scaled.png\" class=\"attachment-full size-full wp-image-37849\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled.png 340w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled-300x300.png 300w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled-150x150.png 150w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled-60x60.png 60w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled-24x24.png 24w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled-36x36.png 36w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gcia_scaled-48x48.png 48w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-ada8c4b\" data-id=\"ada8c4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0df5a80 elementor-widget elementor-widget-image\" data-id=\"0df5a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"340\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/auszeichnungen_gmon_scaled.png\" class=\"attachment-full size-full wp-image-37855\" alt=\"\" srcset=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled.png 340w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled-300x300.png 300w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled-150x150.png 150w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled-60x60.png 60w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled-24x24.png 24w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled-36x36.png 36w, https:\/\/www.secuinfra.com\/wp-content\/uploads\/\/auszeichnungen_gmon_scaled-48x48.png 48w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d67c52d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d67c52d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-67d1b0c\" data-id=\"67d1b0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da0102e gruen elementor-widget elementor-widget-heading\" data-id=\"da0102e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die wichtigsten FAQ aus dem Bereich Data Breach Assessment<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cff16c0 akkordion_gruen elementor-widget elementor-widget-accordion\" data-id=\"cff16c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2181\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2181\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Was ist ein Data Breach Assessment?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2181\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2181\"><p>Das SECUINFRA Data Breach Assessment nutzt Werkzeuge, um gezielt nach Spuren von gestohlenen oder abgeflossenen Daten\/Informationen im Internet und Darknet zu suchen. Durch ein Data Breach Assessment k\u00f6nnen auch kompromittierte IT-Systeme zuverl\u00e4ssig erkannt werden. Durch das schnelle Erkennen einer Kompromittierung k\u00f6nnen fr\u00fchzeitig Gegenma\u00dfnahmen eingeleitet und der Zugriff des Angreifers auf kritische Systeme und Daten unterbunden werden. Gr\u00f6\u00dfere Sch\u00e4den k\u00f6nnen so vermieden werden.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2182\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2182\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Welche Daten ben\u00f6tigen Sie, um uns in den Dienst aufzunehmen?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2182\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2182\"><p>In der Regel werden die Domains Ihres Unternehmens ben\u00f6tigt. Dazu geh\u00f6ren auch Domains von Subunternehmern, ausl\u00e4ndischen Standorten etc. Optional auch die IPs der \u00f6ffentlich zug\u00e4nglichen Systeme sowie die Namen ihrer VIPs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2183\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2183\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Welche Dienstleistungsmodelle bieten Sie an?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2183\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2183\"><p>Generell unterscheiden wir zwischen einem Adhoc- und einem Continuous Scan. Bei einem Adhoc-Scan durchsuchen wir alle Quellen einmalig und pr\u00e4sentieren Ihnen die Ergebnisse. Bei einem Continuous Scan durchsuchen wir alle Quellen regelm\u00e4\u00dfig und informieren Sie sofort, wenn wir einen Fund gemacht haben.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2184\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2184\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Was passiert, wenn ein Ergebnis vorliegt?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2184\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2184\"><p>Dies h\u00e4ngt nat\u00fcrlich vom Ergebnis ab. Sollten Ihre Daten ver\u00f6ffentlicht werden, weil ein Angreifer in Ihr Netzwerk eingedrungen ist, bieten wir Ihnen zus\u00e4tzlich einen Digital Forensics &amp; Incident Response Service an.<\/p><p>Ein weiterer Bestandteil unserer Dienstleistung ist ein Takedown-Service nach dem Best-Effort-Prinzip. Sollte dies in Ihrem Fall nicht m\u00f6glich sein, beraten wir Sie gerne \u00fcber alternative Minderungsma\u00dfnahmen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2185\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2185\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie schnell benachrichtigen Sie mich, wenn ein Befund vorliegt?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2185\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2185\"><p>Unser Team ist rund um die Uhr f\u00fcr Sie erreichbar. Sobald ein Befund festgestellt wird, der ein sofortiges Eingreifen erfordert, werden die zust\u00e4ndigen Personen direkt informiert.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2186\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2186\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie passt der Data Breach Assessment Service in mein bestehendes Sicherheitskonzept?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2186\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2186\"><p>Unser Service f\u00fcgt sich nicht nur nahtlos in bestehende Sicherheitskonzepte Ihres Unternehmens ein, sondern erweitert diese. Das SECUINFRA Data Breach Assessment geht weit \u00fcber die M\u00f6glichkeiten der klassischen Breach Detection hinaus und schlie\u00dft so bestehende L\u00fccken in der Erkennung. Die Bereiche Cyber Threat Intelligence, Digital Risk Protection und External Attack Surface Management werden durch das SECUINFRA Data Breach Assessment abgedeckt.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2187\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2187\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wann ben\u00f6tige ich ein Data Breach Assessment f\u00fcr mein Unternehmen?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2187\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2187\"><p>Der Data Breach Assessment Service von SECUINFRA kann sowohl pr\u00e4ventiv &#8211; ohne bekannte Bedrohungslage &#8211; als auch nach einem bereits eingetretenen Sicherheitsvorfall in Anspruch genommen werden. Letzteres Szenario umfasst beispielsweise Situationen, in denen ein erster Cyber-Angriff auf Ihr Unternehmensnetzwerk best\u00e4tigt wurde und erste Hinweise auf eine Exfiltration von Daten oder zum Verkauf angebotene Zugangsdaten vorliegen. Unser Data Breach Assessment kl\u00e4rt eine m\u00f6gliche Ausnutzung dieser Daten und die damit verbundene Ausbreitung eines Angriffs in Rekordzeit auf und verhindert so hohe Sch\u00e4den.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Was ist ein Data Breach Assessment?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Das SECUINFRA Data Breach Assessment nutzt Werkzeuge, um gezielt nach Spuren von gestohlenen oder abgeflossenen Daten\\\/Informationen im Internet und Darknet zu suchen. Durch ein Data Breach Assessment k\\u00f6nnen auch kompromittierte IT-Systeme zuverl\\u00e4ssig erkannt werden. Durch das schnelle Erkennen einer Kompromittierung k\\u00f6nnen fr\\u00fchzeitig Gegenma\\u00dfnahmen eingeleitet und der Zugriff des Angreifers auf kritische Systeme und Daten unterbunden werden. Gr\\u00f6\\u00dfere Sch\\u00e4den k\\u00f6nnen so vermieden werden.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Welche Daten ben\\u00f6tigen Sie, um uns in den Dienst aufzunehmen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>In der Regel werden die Domains Ihres Unternehmens ben\\u00f6tigt. Dazu geh\\u00f6ren auch Domains von Subunternehmern, ausl\\u00e4ndischen Standorten etc. Optional auch die IPs der \\u00f6ffentlich zug\\u00e4nglichen Systeme sowie die Namen ihrer VIPs.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Welche Dienstleistungsmodelle bieten Sie an?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Generell unterscheiden wir zwischen einem Adhoc- und einem Continuous Scan. Bei einem Adhoc-Scan durchsuchen wir alle Quellen einmalig und pr\\u00e4sentieren Ihnen die Ergebnisse. Bei einem Continuous Scan durchsuchen wir alle Quellen regelm\\u00e4\\u00dfig und informieren Sie sofort, wenn wir einen Fund gemacht haben.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Was passiert, wenn ein Ergebnis vorliegt?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Dies h\\u00e4ngt nat\\u00fcrlich vom Ergebnis ab. Sollten Ihre Daten ver\\u00f6ffentlicht werden, weil ein Angreifer in Ihr Netzwerk eingedrungen ist, bieten wir Ihnen zus\\u00e4tzlich einen Digital Forensics &amp; Incident Response Service an.<\\\/p><p>Ein weiterer Bestandteil unserer Dienstleistung ist ein Takedown-Service nach dem Best-Effort-Prinzip. Sollte dies in Ihrem Fall nicht m\\u00f6glich sein, beraten wir Sie gerne \\u00fcber alternative Minderungsma\\u00dfnahmen.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Wie schnell benachrichtigen Sie mich, wenn ein Befund vorliegt?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Unser Team ist rund um die Uhr f\\u00fcr Sie erreichbar. Sobald ein Befund festgestellt wird, der ein sofortiges Eingreifen erfordert, werden die zust\\u00e4ndigen Personen direkt informiert.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Wie passt der Data Breach Assessment Service in mein bestehendes Sicherheitskonzept?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Unser Service f\\u00fcgt sich nicht nur nahtlos in bestehende Sicherheitskonzepte Ihres Unternehmens ein, sondern erweitert diese. Das SECUINFRA Data Breach Assessment geht weit \\u00fcber die M\\u00f6glichkeiten der klassischen Breach Detection hinaus und schlie\\u00dft so bestehende L\\u00fccken in der Erkennung. Die Bereiche Cyber Threat Intelligence, Digital Risk Protection und External Attack Surface Management werden durch das SECUINFRA Data Breach Assessment abgedeckt.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Wann ben\\u00f6tige ich ein Data Breach Assessment f\\u00fcr mein Unternehmen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Der Data Breach Assessment Service von SECUINFRA kann sowohl pr\\u00e4ventiv &#8211; ohne bekannte Bedrohungslage &#8211; als auch nach einem bereits eingetretenen Sicherheitsvorfall in Anspruch genommen werden. Letzteres Szenario umfasst beispielsweise Situationen, in denen ein erster Cyber-Angriff auf Ihr Unternehmensnetzwerk best\\u00e4tigt wurde und erste Hinweise auf eine Exfiltration von Daten oder zum Verkauf angebotene Zugangsdaten vorliegen. Unser Data Breach Assessment kl\\u00e4rt eine m\\u00f6gliche Ausnutzung dieser Daten und die damit verbundene Ausbreitung eines Angriffs in Rekordzeit auf und verhindert so hohe Sch\\u00e4den.<\\\/p>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2dcc9d hintergrund_gruen verlauf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2dcc9d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0f4223\" data-id=\"e0f4223\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ee0e0 elementor-widget elementor-widget-heading\" data-id=\"63ee0e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Darum SECUINFRA!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2731a6 elementor-widget elementor-widget-mew-icon-slider\" data-id=\"f2731a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mew-icon-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"mew-icon-slider\">\n\t\t\t\t\t<div class=\"mew-icon-slider-item\">\n\t\t\t\t<div class=\"mew-icon-slider-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-thumbnail\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/13_expertise.png\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-title\">\n\t\t\t\t\t\tEXPERTISE\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-text\">\n\t\t\t\t\t\t<p>Einschl\u00e4gige Schulungen und Zertifizierungen, aber vor allen st\u00e4ndige Incident-Response-Eins\u00e4tze haben dazu beigetragen, dass unsere Incident Responder \u00fcber die Jahre ein enormes Expertenwissen aufbauen konnten<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mew-icon-slider-item\">\n\t\t\t\t<div class=\"mew-icon-slider-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-thumbnail\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/14_verfuegbarkeit.png\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-title\">\n\t\t\t\t\t\tVERF\u00dcGBARKEIT\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-text\">\n\t\t\t\t\t\t<p class=\"inhalt\">SECUINFRA verf\u00fcgt \u00fcber eines der schlagkr\u00e4ftigsten Incident-Response-Experten-Teams in Europa. Rahmenvertr\u00e4ge garantieren Ihnen jederzeit die Verf\u00fcgbarkeit unserer Incident-Response-Experten.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mew-icon-slider-item\">\n\t\t\t\t<div class=\"mew-icon-slider-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-thumbnail\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/15_professionalitaet.png\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-title\">\n\t\t\t\t\t\tPROFESSIONALIT\u00c4T\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-text\">\n\t\t\t\t\t\t<p class=\"inhalt\">Incident Response geh\u00f6rt zu den Kernkompetenzen von SECUINFRA - Made in Germany. \u00dcber die Jahre haben wir unsere Methoden, Prozesse und Tools immer weiter perfektioniert, um Ihnen jederzeit einen professionellen Service bieten zu k\u00f6nnen.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"mew-icon-slider-item\">\n\t\t\t\t<div class=\"mew-icon-slider-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-thumbnail\">\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/16_vorbereitung.png\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-title\">\n\t\t\t\t\t\tVORBEREITUNG\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"mew-icon-slider-text\">\n\t\t\t\t\t\t<p>Bei allen Kunden im Bereich Incident Response f\u00fchren wir ein Onboarding durch, um sie auf den Ernstfall vorzubereiten. Dies stellt sicher, dass sie im Ernstfall stets die Nerven behalten und die richtigen Entscheidungen treffen.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-bd5f715 e-flex e-con-boxed e-con e-parent\" data-id=\"bd5f715\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01cf99a elementor-widget elementor-widget-heading\" data-id=\"01cf99a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weitere informative Blogbeitr\u00e4ge und Fachartikel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d84790 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"9d84790\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:54713,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-64107 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-64107 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/PYTHON_MALWARE_Header-scaled.png\");}<\/style><style id=\"loop-54713\">.elementor-54713 .elementor-element.elementor-element-238b6e3{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--align-items:center;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-54713 .elementor-element.elementor-element-befb43b{--display:flex;--min-height:200px;--overflow:hidden;--border-radius:20px 20px 20px 20px;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-54713 .elementor-element.elementor-element-a800ba8{--display:flex;--min-height:200px;--overflow:hidden;--background-transition:0.3s;border-style:none;--border-style:none;--margin-top:0px;--margin-bottom:0px;--margin-left:0px;--margin-right:0px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-54713 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .elementor-54713 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-54713 .elementor-element.elementor-element-a800ba8.e-con{--align-self:center;}.elementor-54713 .elementor-element.elementor-element-9c0c3ba{text-align:center;}.elementor-54713 .elementor-element.elementor-element-9c0c3ba .elementor-heading-title{font-size:18px;color:var( --e-global-color-5df85b9 );}@media(max-width:767px){.elementor-54713 .elementor-element.elementor-element-a800ba8{--width:80%;}}@media(min-width:768px){.elementor-54713 .elementor-element.elementor-element-befb43b{--width:300px;}}\/* Start custom CSS for container, class: .elementor-element-a800ba8 *\/.elementor-54713 .elementor-element.elementor-element-a800ba8:hover {\n    \/*max-width: 100%;*\/\n}\/* End custom CSS *\/\n\/* Start custom CSS for container, class: .elementor-element-238b6e3 *\/.elementor-54713 .elementor-element.elementor-element-238b6e3:hover .post_bg-image {\n    transform: scale(1.1);\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-64107 post-64107 post type-post status-publish format-standard has-post-thumbnail hentry category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/von-svchoss-bis-payday\/\">Von &#8217;svchoss&#8216; zu P(a)yday<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-63899 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-63899 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/stealer-title.png\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-63899 post-63899 post type-post status-publish format-standard has-post-thumbnail hentry category-incident-response category-techtalk tag-analysis tag-clickfix tag-infostealer tag-it-security tag-malware-2\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/clickfix-und-infostealer-frisch-vom-grill\/\">Clickfix und Infostealer frisch vom Grill<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-54000 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-54000 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/iStock-1399210071-scaled.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-54000 post-54000 post type-post status-publish format-standard has-post-thumbnail hentry category-incident-response category-techtalk tag-incident-readiness\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/ist-ihre-organisation-wirklich-auf-einen-cybervorfall-vorbereitet\/\">Ist Ihre Organisation wirklich auf einen Cybervorfall vorbereitet?<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-54229 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-54229 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Kopie-von-Cream-and-Brown-Photographic-Beauty-Site-Launch-Website.png\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-54229 post-54229 post type-post status-publish format-standard has-post-thumbnail hentry category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/wenn-der-portscan-legitim-ist-lessons-learned-aus-keinem-incident\/\">Wenn der Portscan legitim ist: Lesson-Learned aus (k)einem Incident<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-49001 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-49001 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/pexels-morais-90628-scaled.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-49001 post-49001 post type-post status-publish format-standard has-post-thumbnail hentry category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/cisco-ios-xe-schwachstelle-cve-2023-20198-tausende-internet-exponierte-appliances-wohl-bereits-kompromittiert\/\">Cisco IOS XE Schwachstelle CVE-2023-20198 \u2013 tausende Internet-exponierte Appliances wohl bereits kompromittiert!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-36851 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-36851 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/esxiargs-title-scaled.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-36851 post-36851 post type-post status-publish format-standard has-post-thumbnail hentry category-incident-response category-sicherheitsluecken category-techtalk tag-analyse-2 tag-esxiargs-2 tag-malware-2 tag-ransomware-2\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/hide-your-hypervisor-analyse-von-esxiargs-ransomware\/\">Hide your Hypervisor: Analyse von ESXiArgs Ransomware<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-36375 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-36375 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/cyberangriff-erfolgreich.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-36375 post-36375 post type-post status-publish format-standard has-post-thumbnail hentry category-compromise-assessment category-digital-forensics category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/cyberangriff-erfolgreich-welche-3-teildisziplinen-der-it-security-jetzt-gebraucht-werden\/\">Cyberangriff erfolgreich \u2013 Welche 3 Teildisziplinen der IT Security jetzt gebraucht werden!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-25712 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-25712 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/n-worm-analyse_2.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-25712 post-25712 post type-post status-publish format-standard has-post-thumbnail hentry category-digital-forensics category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/n-w0rm-analyse-teil-2\/\">N-W0rm Analyse (Teil 2)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-25688 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-25688 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/N_W0RM-Analyse_1.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-25688 post-25688 post type-post status-publish format-standard has-post-thumbnail hentry category-digital-forensics category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/n-w0rm-analyse-teil-1\/\">N-W0rm Analyse (Teil 1)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<style id=\"loop-dynamic-54713\">.e-loop-item-15298 .elementor-element.elementor-element-a800ba8:not(.elementor-motion-effects-element-type-background), .e-loop-item-15298 .elementor-element.elementor-element-a800ba8 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/iStock-1340100025.jpg\");}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"54713\" class=\"elementor elementor-54713 swiper-slide e-loop-item e-loop-item-15298 post-15298 post type-post status-publish format-standard has-post-thumbnail hentry category-digital-forensics category-incident-response category-techtalk\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-238b6e3 e-flex e-con-boxed e-con e-parent\" data-id=\"238b6e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-befb43b e-con-full e-flex e-con e-child\" data-id=\"befb43b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a800ba8 e-con-full post_bg-image e-flex e-con e-child\" data-id=\"a800ba8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0c3ba elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"9c0c3ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.secuinfra.com\/de\/techtalk\/meldepfilchten-bei-einem-it-security-incident\/\">Meldepflichten bei einem IT Security Incident<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2eb41 elementor-widget elementor-widget-spacer\" data-id=\"4b2eb41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ecd410 elementor-widget elementor-widget-spacer\" data-id=\"2ecd410\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-540b76c hintergrund_grau elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"540b76c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d4a292\" data-id=\"0d4a292\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf93e87 gruen elementor-widget elementor-widget-heading\" data-id=\"bf93e87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Referenzen im Bereich Incident Management<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dcb9aa pfeile_gruen elementor-widget elementor-widget-text-editor\" data-id=\"6dcb9aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>VERSCHWIEGENHEIT<br \/><\/strong>SECUINFRA benennt weder Kunden noch Referenzen \u00f6ffentlich! Der Wunsch unserer Kunden nach Verschwiegenheit steht jederzeit \u00fcber den Marketinginteressen von SECUINFRA.<\/p><\/li><li><p><strong>ERFOLG DURCH EMPFEHLUNG<br \/><\/strong>Die SECUINFRA DFIR-Teams unterst\u00fctzen seit Jahren Tag f\u00fcr Tag Unternehmen im Bereich <span class=\"nobreak\">digitale Forensik<\/span> und <span class=\"nobreak\">Incident Response (DFIR).<\/span>Mehr als 7000 Unternehmen in Deutschland vertrauen SECUINFRA direkt oder \u00fcber Partner im Bereich <span class=\"nobreak\">digitale Forensik<\/span> und <span class=\"nobreak\">Incident Response (DFIR).<\/span><\/p><\/li><li><p><strong>REFERENZ AUF ANFRAGE<br \/><\/strong>Bei berechtigtem Interesse stellen wir den Kontakt zu passenden Referenzkunden her.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3888ec3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3888ec3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-608c959\" data-id=\"608c959\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9139550 elementor-widget elementor-widget-template\" data-id=\"9139550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"46888\" class=\"elementor elementor-46888\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70b9ca1 e-flex e-con-boxed e-con e-parent\" data-id=\"70b9ca1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b52501 elementor-widget elementor-widget-menu-anchor\" data-id=\"0b52501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"contact\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25dbd5e5 e-flex e-con-boxed e-con e-parent\" data-id=\"25dbd5e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e2bb1bf e-con-full bubble_box elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"e2bb1bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4deb1860 elementor-widget elementor-widget-image\" data-id=\"4deb1860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"45\" height=\"56\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/sprechblase-weiss.svg\" class=\"attachment-full size-full wp-image-46900\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1adf6f16 e-con-full e-flex e-con e-child\" data-id=\"1adf6f16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b84146 e-con-full e-flex e-con e-child\" data-id=\"7b84146\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f3982c8 e-con-full e-flex e-con e-child\" data-id=\"f3982c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ebd7d9d e-con-full bubble_box elementor-hidden-desktop e-flex e-con e-child\" data-id=\"ebd7d9d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75c0a36 elementor-widget elementor-widget-image\" data-id=\"75c0a36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"45\" height=\"56\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/sprechblase-weiss.svg\" class=\"attachment-full size-full wp-image-46900\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ddb84cc e-con-full e-flex e-con e-child\" data-id=\"ddb84cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f6a40ca elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6f6a40ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nNehmen Sie hier\nKontakt zu uns auf!\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc6441c elementor-widget elementor-widget-shortcode\" data-id=\"5dc6441c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_3' >\n                        <div class='gform_heading'>\n                            <h2 class=\"gform_title\">Kontaktformular Seitenende<\/h2>\n                            <p class='gform_description'>Kontaktformular am Seitenende<\/p>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>\u201e<span class=\"gfield_required gfield_required_asterisk\">*<\/span>\u201c zeigt erforderliche Felder an<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_3'  action='\/de\/wp-json\/wp\/v2\/pages\/51021' data-formid='3' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_1\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_1'>Vorname:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_3_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_3\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_3'>Nachname:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_3_3' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_4\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_4'>Unternehmen:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_3_4' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_11\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_11'>E-Mail<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_11' id='input_3_11' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_3_9\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_9'>Telefon:<\/label><div class='ginput_container ginput_container_text'><input name='input_9' id='input_3_9' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_7\" class=\"gfield gfield--type-select gfield--input-type-select gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_7'>T\u00e4tigkeit im Unternehmen:<\/label><div class='ginput_container ginput_container_select'><select name='input_7' id='input_3_7' class='large gfield_select'     aria-invalid=\"false\" ><option value='Bitte ausw\u00e4hlen...' >Bitte ausw\u00e4hlen...<\/option><option value='CIO' >CIO<\/option><option value='CISO' >CISO<\/option><option value='IT-Leiter\/-in' >IT-Leiter\/-in<\/option><option value='Sicherheitsbeauftragte\/-r' >Sicherheitsbeauftragte\/-r<\/option><option value='Administrator\/-in' >Administrator\/-in<\/option><option value='Berater\/-in' >Berater\/-in<\/option><option value='Sonstige' >Sonstige<\/option><\/select><\/div><\/div><div id=\"field_3_14\" class=\"gfield gfield--type-select gfield--input-type-select gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_14'>Wie sind Sie auf uns aufmerksam geworden?<\/label><div class='ginput_container ginput_container_select'><select name='input_14' id='input_3_14' class='large gfield_select'     aria-invalid=\"false\" ><option value='Bitte ausw\u00e4hlen...' >Bitte ausw\u00e4hlen...<\/option><option value='Empfehlung' >Empfehlung<\/option><option value='Online-Suche' >Online-Suche<\/option><option value='Soziale Medien' >Soziale Medien<\/option><option value='Veranstaltungen' >Veranstaltungen<\/option><option value='Presse\/Medien' >Presse\/Medien<\/option><option value='Partnerschaften' >Partnerschaften<\/option><option value='Direkter Kontakt' >Direkter Kontakt<\/option><option value='Sonstiges' >Sonstiges<\/option><\/select><\/div><\/div><div id=\"field_3_12\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield--width-full bold_label field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_12'>Ihre Bemerkungen, Fragen oder W\u00fcnsche:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_12' id='input_3_12' class='textarea medium'  aria-describedby=\"gfield_description_3_12\"    aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><div class='gfield_description' id='gfield_description_3_12'>Bitte konkretisieren Sie Ihre Anfrage, damit wir sie schnell an die richtigen Ansprechpartner weiterleiten k\u00f6nnen. <\/div><\/div><fieldset id=\"field_3_13\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Einwilligung zur Datennutzung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_13.1' id='input_3_13_1' type='checkbox' value='1'   aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_3_13_1' >Hiermit stimme ich der <a target=\"_blank\" href=\"https:\/\/www.secuinfra.com\/de\/privacy-policy\/\">Datenschutzerkl\u00e4rung<\/a> dieser Webseite zu.<\/label><input type='hidden' name='input_13.2' value='Hiermit stimme ich der &lt;a target=&quot;_blank&quot; href=&quot;https:\/\/www.secuinfra.com\/de\/privacy-policy\/&quot;&gt;Datenschutzerkl\u00e4rung&lt;\/a&gt; dieser Webseite zu.' class='gform_hidden' \/><input type='hidden' name='input_13.3' value='3' class='gform_hidden' \/><\/div><\/fieldset><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_3' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Absenden'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_3' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_3' id='gform_theme_3' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_3' id='gform_style_settings_3' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_3' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='3' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='8gLDPMKRPcVLhe0fgHnZnVx6oKd4K8vPTx5kIL9YOK+GEAXxsymmU3K0PUEYZbKYamPRRjhc3WTM1dGlyZGg8qK9\/aJAwAV0Iq639iEnN4gOV1U=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_3' value='WyJ7XCIxNFwiOltcIjY0MTY2YWFjZDU5ZjQzYmI3NDZhZWNkMDBjMTI3ODdjXCIsXCIyNDRjZGM0NGNjMjRiZTUzY2YyMDI0OWYwNjA3OTFjM1wiLFwiZDUxMmY2NjA5MmY5NDhlODc1NjEzMWY2MDNjY2YyZTRcIixcImZhZTZkNDc1YWQ2ZjdiMGI0ZTMxNjcwYTkxZjQyYjJjXCIsXCI2YjljODFhNTAyZmZkMDVmNTNhNDhlZThiYzRjMWM5ZlwiLFwiNDQyZDdjZWUwMjlhN2Y3ZDA2NGQ2MGY0YjdkMzlhYzdcIixcImRhZDU1NDY2NWFhZDQwNmRiMmI2YzQ2NjkxMWJlYTE3XCIsXCIyODNmZjY3ZDAyYmJlZjg2MWE3NGJmNTczZmMzZDk0ZlwiLFwiMTk5OTYwOTY3ZWFiMWNiMzlmNDFlZDUzOTcyZmQ3MGFcIl0sXCIxMy4xXCI6XCI1MmFhNzk3MDRjN2RmNzQwYmUwYjFmZWQ3ZmRmZGFiOVwiLFwiMTMuMlwiOlwiODNiMWE4MDM5OGVlYmMxNTY0MzMwMjc1YmQxZjhlNmJcIixcIjEzLjNcIjpcIjI1NGI0MWFjNmM3Y2RkMzI3MDg3NzI5YzZiMjczZTczXCJ9IiwiMjZiN2E2ZTM1YjBiNmFhM2I1OGU5ZDQwY2VlZjMxMDIiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_3' id='gform_target_page_number_3' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_3' id='gform_source_page_number_3' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 3, 'https:\/\/www.secuinfra.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_3').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_3');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_3').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_3').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_3').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_3').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_3').val();gformInitSpinner( 3, 'https:\/\/www.secuinfra.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [3, current_page]);window['gf_submitting_3'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_3').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [3]);window['gf_submitting_3'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_3').text());}else{jQuery('#gform_3').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"3\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_3\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_3\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_3\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 3, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1f75758 e-con-full animated-slow elementor-hidden-tablet elementor-hidden-desktop e-flex e-con e-parent\" data-id=\"1f75758\" data-element_type=\"container\" data-e-type=\"container\" id=\"hilfe_mobile\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ac37e20 e-con-full e-flex e-con e-child\" data-id=\"ac37e20\" data-element_type=\"container\" data-e-type=\"container\" id=\"hilfe_text\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f49a35 gruen elementor-widget elementor-widget-heading\" data-id=\"4f49a35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Schnelle Hilfe\nim Notfall!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e0c969 gruen elementor-widget elementor-widget-heading\" data-id=\"9e0c969\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">+49 30 555702 112\nincident@secuinfra.com<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-683ae63 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"683ae63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"93\" height=\"97\" src=\"https:\/\/www.secuinfra.com\/wp-content\/uploads\/ISO_gruen.svg\" class=\"attachment-full size-full wp-image-39836\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8dd0083 e-con-full e-flex e-con e-child\" data-id=\"8dd0083\" data-element_type=\"container\" data-e-type=\"container\" id=\"hilfe_button\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b93d74 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2b93d74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-volume\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M97.333 506.966c-129.874-129.874-129.681-340.252 0-469.933 5.698-5.698 14.527-6.632 21.263-2.422l64.817 40.513a17.187 17.187 0 0 1 6.849 20.958l-32.408 81.021a17.188 17.188 0 0 1-17.669 10.719l-55.81-5.58c-21.051 58.261-20.612 122.471 0 179.515l55.811-5.581a17.188 17.188 0 0 1 17.669 10.719l32.408 81.022a17.188 17.188 0 0 1-6.849 20.958l-64.817 40.513a17.19 17.19 0 0 1-21.264-2.422zM247.126 95.473c11.832 20.047 11.832 45.008 0 65.055-3.95 6.693-13.108 7.959-18.718 2.581l-5.975-5.726c-3.911-3.748-4.793-9.622-2.261-14.41a32.063 32.063 0 0 0 0-29.945c-2.533-4.788-1.65-10.662 2.261-14.41l5.975-5.726c5.61-5.378 14.768-4.112 18.718 2.581zm91.787-91.187c60.14 71.604 60.092 175.882 0 247.428-4.474 5.327-12.53 5.746-17.552.933l-5.798-5.557c-4.56-4.371-4.977-11.529-.93-16.379 49.687-59.538 49.646-145.933 0-205.422-4.047-4.85-3.631-12.008.93-16.379l5.798-5.557c5.022-4.813 13.078-4.394 17.552.933zm-45.972 44.941c36.05 46.322 36.108 111.149 0 157.546-4.39 5.641-12.697 6.251-17.856 1.304l-5.818-5.579c-4.4-4.219-4.998-11.095-1.285-15.931 26.536-34.564 26.534-82.572 0-117.134-3.713-4.836-3.115-11.711 1.285-15.931l5.818-5.579c5.159-4.947 13.466-4.337 17.856 1.304z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Data Breach Assessment Identifizieren Sie gestohlene Daten bevor Angreifer sie gezielt ausnutzen! Erkennen Sie Datenlecks so fr\u00fch wie m\u00f6glich, unabh\u00e4ngig davon, ob sie intern oder durch Dritte entstanden sind. Verstehen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":62305,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"dpc_author_order":[],"footnotes":""},"class_list":["post-51021","page","type-page","status-publish","hentry","page-color-template-green_template"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/pages\/51021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/comments?post=51021"}],"version-history":[{"count":10,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/pages\/51021\/revisions"}],"predecessor-version":[{"id":65531,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/pages\/51021\/revisions\/65531"}],"up":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/pages\/62305"}],"wp:attachment":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media?parent=51021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}