{"id":57048,"date":"2025-02-17T15:59:52","date_gmt":"2025-02-17T14:59:52","guid":{"rendered":"https:\/\/www.secuinfra.com\/?p=57048"},"modified":"2025-02-17T15:59:56","modified_gmt":"2025-02-17T14:59:56","slug":"secuinfra-auf-der-elastic-roadshow-in-frankfurt-2025","status":"publish","type":"post","link":"https:\/\/www.secuinfra.com\/de\/news\/secuinfra-auf-der-elastic-roadshow-in-frankfurt-2025\/","title":{"rendered":"SECUINFRA auf der Elastic Roadshow in Frankfurt 2025"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-flat ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">[inhalt_uebersetzt]<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.secuinfra.com\/de\/news\/secuinfra-auf-der-elastic-roadshow-in-frankfurt-2025\/#Warum_sich_die_Teilnahme_lohnt\" >Warum sich die Teilnahme lohnt<\/a><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">Am <strong>6. M\u00e4rz 2025<\/strong> macht die <strong>Elastic Roadshow<\/strong> Halt in Frankfurt \u2013 eine Veranstaltung, die Fachwissen, Innovation und Praxisn\u00e4he vereint. SECUINFRA ist als <strong>Sponsor<\/strong> mit dabei und unterstreicht damit sein Engagement f\u00fcr hochmoderne Sicherheitsl\u00f6sungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Warum_sich_die_Teilnahme_lohnt\"><\/span>Warum sich die Teilnahme lohnt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Elastic Roadshow bietet tiefgehende Einblicke in aktuelle Entwicklungen in den Bereichen <strong>Observability und Security<\/strong>. Besonders im Fokus stehen die <strong>AI-Assistants<\/strong> von Elastic, die mithilfe von <strong>Generative AI und tiefgehenden Infrastruktur-Analysen<\/strong> Sicherheitsteams wie <strong>Security Operations Centers (SOC)<\/strong> und <strong>Site Reliability Engineers (SRE)<\/strong> dabei unterst\u00fctzen, Bedrohungen schneller zu erkennen und effizient zu bek\u00e4mpfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neben <strong>praxisnahen Sessions<\/strong> mit Elastic-Experten, <strong>Live-Demonstrationen<\/strong> innovativer Technologien und <strong>Kundenvortr\u00e4gen<\/strong> bietet die Roadshow die Gelegenheit zum <strong>Networking mit Branchenkollegen und Vordenkern<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein besonderes Highlight ist der Vortrag von <strong>Florian Schmid<\/strong>, Senior Cyber Defense Consultant bei <strong>SECUINFRA<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>XDR: Weil selbst Superman einen Sidekick braucht<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>In der heutigen, sich rasant entwickelnden Bedrohungslandschaft ben\u00f6tigen Sicherheitsteams mehr als nur traditionelle SIEM-L\u00f6sungen. Diese Pr\u00e4sentation zeigt, wie die Kombination von Elastic SIEM mit Elastic XDR eine leistungsstarke und effiziente Sicherheitsmanagement erm\u00f6glicht. Wir werden erl\u00e4utern, wie XDR fortschrittliche Bedrohungserkennungsfunktionen nutzt, um raffinierte Angriffe zu identifizieren und darauf zu reagieren \u2013 Angriffe, die herk\u00f6mmliche Sicherheitsma\u00dfnahmen oft umgehen.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Elastic Roadshow in Frankfurt ist eine einzigartige Gelegenheit, um <strong>zukunftsweisende Sicherheitsstrategien<\/strong> kennenzulernen, sich mit Experten auszutauschen und tiefgehende Einblicke in die neuesten Technologien zu erhalten. Die Pl\u00e4tze sind begrenzt \u2013 <strong>jetzt anmelden!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen zur ElasticON Tour und die Anmeldung finden Sie <a  href=\"https:\/\/events.elastic.co\/elasticroadshowfrankfurt2025\"  target=\"_blank\" rel=\"noreferrer noopener\" dpc-external=\"true\"  target=\"_blank\"  rel=\"nofollow\" >hier<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 6. M\u00e4rz 2025 macht die Elastic Roadshow Halt in Frankfurt \u2013 eine Veranstaltung, die Fachwissen, Innovation und Praxisn\u00e4he vereint. SECUINFRA ist als Sponsor mit dabei und unterstreicht damit sein Engagement f\u00fcr hochmoderne Sicherheitsl\u00f6sungen.<\/p>\n","protected":false},"author":33,"featured_media":57049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"dpc_author_order":[],"footnotes":""},"categories":[1],"tags":[356],"class_list":["post-57048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cybersecurity-trends"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts\/57048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/comments?post=57048"}],"version-history":[{"count":0,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts\/57048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media\/57049"}],"wp:attachment":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media?parent=57048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/categories?post=57048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tags?post=57048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}