{"id":61358,"date":"2025-10-15T15:10:00","date_gmt":"2025-10-15T13:10:00","guid":{"rendered":"https:\/\/www.secuinfra.com\/?p=61358"},"modified":"2025-10-20T17:42:18","modified_gmt":"2025-10-20T15:42:18","slug":"teletrust-podcast-cyber-resilienz-in-der-praxis-secuinfra-experte-david-bischoff-ueber-wirksames-incident-management","status":"publish","type":"post","link":"https:\/\/www.secuinfra.com\/de\/news\/teletrust-podcast-cyber-resilienz-in-der-praxis-secuinfra-experte-david-bischoff-ueber-wirksames-incident-management\/","title":{"rendered":"TeleTrusT-Podcast: Cyber-Resilienz in der Praxis \u2013 SECUINFRA-Experte David Bischoff \u00fcber wirksames Incident Management"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Cyber-Resilienz<\/strong> ist l\u00e4ngst mehr als ein Schlagwort: Sie ist eine strategische Notwendigkeit f\u00fcr jedes Unternehmen, das seine digitale Zukunft sichern will. Der aktuelle <strong>TeleTrusT-Podcast<\/strong> widmet sich genau dieser Herausforderung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der neuen Folge spricht David Bischoff, Senior Cyber Defense Consultant bei SECUINFRA, gemeinsam mit Carsten Vossel (CCVOSSEL) und Svenja Mischur (sequrium) dar\u00fcber, wie Organisationen aus <strong>Sicherheitsvorf\u00e4llen<\/strong> lernen, nachhaltige Schutzmechanismen aufbauen und ihre Widerstandsf\u00e4higkeit gegen\u00fcber <strong>Cyberangriffen<\/strong> gezielt steigern k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Gespr\u00e4ch wird deutlich: Cyber-Resilienz entsteht nicht zuf\u00e4llig \u2013 sie ist das Ergebnis systematischer Analyse, klarer Prozesse und eines kontinuierlichen Lernprozesses. Anhand praxisnaher Beispiele zeigt David Bischoff, wie Unternehmen durch gezieltes <strong>Incident Management <\/strong>und strukturierte <strong>Post-Incident-Analysen<\/strong> Schwachstellen erkennen, Risiken bewerten und daraus wirkungsvolle Ma\u00dfnahmen ableiten k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch der <strong>Faktor Mensch<\/strong> spielt dabei eine entscheidende Rolle. Nur wenn Verantwortliche im Unternehmen Prozesse verstehen, Priorit\u00e4ten richtig setzen und Sicherheitsma\u00dfnahmen konsequent umsetzen, l\u00e4sst sich die digitale Resilienz nachhaltig festigen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der TeleTrusT-Podcast bietet wertvolle Impulse f\u00fcr IT-Entscheider, die ihre Sicherheitsstrategie weiterentwickeln wollen \u2013 von der fundierten Bestandsaufnahme der IT-Infrastruktur \u00fcber die Priorisierung von Sicherheitsma\u00dfnahmen bis hin zur Entwicklung strategischer Roadmaps f\u00fcr eine widerstandsf\u00e4hige <strong>IT-Sicherheitslandschaft<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jetzt reinh\u00f6ren und erfahren, wie Cyber-Resilienz in der Praxis gelingt: <a  href=\"https:\/\/www.teletrust.de\/podcasts\/\"  target=\"_blank\" rel=\"noreferrer noopener\" dpc-external=\"true\"  target=\"_blank\"  rel=\"nofollow\" >Zum TeleTrusT-Podcast<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cyber-Resilienz ist l\u00e4ngst mehr als ein Schlagwort: Sie ist eine strategische Notwendigkeit f\u00fcr jedes Unternehmen, das seine digitale Zukunft sichern will. Der aktuelle TeleTrusT-Podcast widmet sich genau dieser Herausforderung.<\/p>\n","protected":false},"author":33,"featured_media":61384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"dpc_author_order":[],"footnotes":""},"categories":[1],"tags":[794],"class_list":["post-61358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cyber-resilienz"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts\/61358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/comments?post=61358"}],"version-history":[{"count":1,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts\/61358\/revisions"}],"predecessor-version":[{"id":61363,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/posts\/61358\/revisions\/61363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media\/61384"}],"wp:attachment":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media?parent=61358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/categories?post=61358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tags?post=61358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}