{"id":64941,"date":"2026-05-18T15:06:08","date_gmt":"2026-05-18T13:06:08","guid":{"rendered":"https:\/\/www.secuinfra.com\/?post_type=tribe_events&#038;p=64941"},"modified":"2026-05-18T16:41:52","modified_gmt":"2026-05-18T14:41:52","slug":"gsx-2026","status":"publish","type":"tribe_events","link":"https:\/\/www.secuinfra.com\/de\/event\/gsx-2026\/","title":{"rendered":"GSX 2026"},"content":{"rendered":"<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"6b8728c1-41c4-42b6-a119-b359f111ef62\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"53\" data-end=\"303\">Die GSX 2026 z\u00e4hlt zu den international f\u00fchrenden Veranstaltungen rund um Security, Resilience und moderne Sicherheitsstrategien. Wir freuen uns, in diesem Jahr vor Ort vertreten zu sein und unsere Expertise im Rahmen eines Fachvortrags einzubringen.<\/p>\n<p data-start=\"305\" data-end=\"734\">Im Mittelpunkt stehen aktuelle Herausforderungen der Cyber Defense, praxisnahe Einblicke aus realen Sicherheitsvorf\u00e4llen sowie Strategien, mit denen Unternehmen ihre digitale Resilienz nachhaltig st\u00e4rken k\u00f6nnen. Gemeinsam mit internationalen Sicherheitsexperten, Entscheidern und Branchenvertretern diskutieren wir \u00fcber moderne Bedrohungslagen, effektive Detection-&amp;-Response-Ans\u00e4tze und zukunftssichere Sicherheitsarchitekturen.<\/p>\n<p data-start=\"736\" data-end=\"927\">Die GSX 2026 bietet die ideale Plattform f\u00fcr den Austausch \u00fcber innovative Sicherheitskonzepte, operative Exzellenz und die Anforderungen einer zunehmend komplexen Cyber-Bedrohungslandschaft.<\/p>\n<p data-start=\"929\" data-end=\"1025\" data-is-last-node=\"\" data-is-only-node=\"\">Wir freuen uns auf inspirierende Gespr\u00e4che, neue Impulse und den pers\u00f6nlichen Austausch vor Ort.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die GSX 2026 z\u00e4hlt zu den international f\u00fchrenden Veranstaltungen rund um Security, Resilience und moderne Sicherheitsstrategien. Wir freuen uns, in diesem Jahr vor Ort vertreten zu sein und unsere Expertise [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":65034,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","dpc_author_order":[],"footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-64941","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tribe_events\/64941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/users\/33"}],"version-history":[{"count":1,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tribe_events\/64941\/revisions"}],"predecessor-version":[{"id":64944,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tribe_events\/64941\/revisions\/64944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media\/65034"}],"wp:attachment":[{"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/media?parent=64941"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tags?post=64941"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.secuinfra.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=64941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}